{"id":8339,"date":"2023-10-22T17:37:27","date_gmt":"2023-10-22T17:37:27","guid":{"rendered":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144.jpg"},"modified":"2023-10-22T17:37:27","modified_gmt":"2023-10-22T17:37:27","slug":"img_20231020_124144","status":"inherit","type":"attachment","link":"https:\/\/www.ugt.cat\/jubilats\/consell-ujp-ugt-de-catalunya-5\/img_20231020_124144\/","title":{"rendered":"IMG_20231020_124144"},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-8339","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"134\" src=\"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-300x134.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-300x134.jpg 300w, https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-1024x459.jpg 1024w, https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-768x344.jpg 768w, https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-1536x688.jpg 1536w, https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-2048x918.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1147,"file":"2023\/10\/IMG_20231020_124144-scaled.jpg","filesize":326406,"sizes":{"medium":{"file":"IMG_20231020_124144-300x134.jpg","width":300,"height":134,"filesize":48972,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-300x134.jpg"},"large":{"file":"IMG_20231020_124144-1024x459.jpg","width":1024,"height":459,"filesize":103603,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-1024x459.jpg"},"thumbnail":{"file":"IMG_20231020_124144-150x150.jpg","width":150,"height":150,"filesize":45794,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-150x150.jpg"},"medium_large":{"file":"IMG_20231020_124144-768x344.jpg","width":768,"height":344,"filesize":79937,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-768x344.jpg"},"1536x1536":{"file":"IMG_20231020_124144-1536x688.jpg","width":1536,"height":688,"filesize":161216,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-1536x688.jpg"},"2048x2048":{"file":"IMG_20231020_124144-2048x918.jpg","width":2048,"height":918,"filesize":235184,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-2048x918.jpg"},"post-thumbnail":{"file":"IMG_20231020_124144-300x125.jpg","width":300,"height":125,"filesize":48467,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-300x125.jpg"},"featured-header":{"file":"IMG_20231020_124144-300x125.jpg","width":300,"height":125,"filesize":48467,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-300x125.jpg"},"featured-slider":{"file":"IMG_20231020_124144-644x320.jpg","width":644,"height":320,"filesize":73289,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-644x320.jpg"},"full":{"file":"IMG_20231020_124144-scaled.jpg","width":2560,"height":1147,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-scaled.jpg"}},"image_meta":{"aperture":"1.79","credit":"","camera":"M2103K19G","caption":"","created_timestamp":"1697805704","copyright":"","focal_length":"4.695","iso":"118","shutter_speed":"0.030006","title":"","orientation":"1","keywords":[]},"original_image":"IMG_20231020_124144.jpg"},"post":8328,"source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2023\/10\/IMG_20231020_124144-scaled.jpg","filename":"IMG_20231020_124144.jpg","filesize":326406,"_links":{"self":[{"href":"https:\/\/www.ugt.cat\/jubilats\/wp-json\/wp\/v2\/media\/8339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ugt.cat\/jubilats\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.ugt.cat\/jubilats\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.ugt.cat\/jubilats\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ugt.cat\/jubilats\/wp-json\/wp\/v2\/comments?post=8339"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":8328,"href":"https:\/\/www.ugt.cat\/jubilats\/wp-json\/wp\/v2\/posts\/8328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}