{"id":9183,"date":"2024-06-16T21:46:12","date_gmt":"2024-06-16T21:46:12","guid":{"rendered":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502.jpg"},"modified":"2024-06-16T21:46:12","modified_gmt":"2024-06-16T21:46:12","slug":"img_20240603_100502","status":"inherit","type":"attachment","link":"https:\/\/www.ugt.cat\/jubilats\/celebrades-les-assemblees-congressuals-dujp-ugt-de-catalunya\/img_20240603_100502\/","title":{"rendered":"IMG_20240603_100502"},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-9183","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"224\" src=\"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-300x224.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-300x224.jpg 300w, https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-1024x766.jpg 1024w, https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-768x574.jpg 768w, https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-1536x1149.jpg 1536w, https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-2048x1532.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1915,"file":"2024\/06\/IMG_20240603_100502-scaled.jpg","filesize":795661,"sizes":{"medium":{"file":"IMG_20240603_100502-300x224.jpg","width":300,"height":224,"filesize":45954,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-300x224.jpg"},"large":{"file":"IMG_20240603_100502-1024x766.jpg","width":1024,"height":766,"filesize":182838,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-1024x766.jpg"},"thumbnail":{"file":"IMG_20240603_100502-150x150.jpg","width":150,"height":150,"filesize":35289,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-150x150.jpg"},"medium_large":{"file":"IMG_20240603_100502-768x574.jpg","width":768,"height":574,"filesize":120344,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-768x574.jpg"},"1536x1536":{"file":"IMG_20240603_100502-1536x1149.jpg","width":1536,"height":1149,"filesize":344877,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-1536x1149.jpg"},"2048x2048":{"file":"IMG_20240603_100502-2048x1532.jpg","width":2048,"height":1532,"filesize":550940,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-2048x1532.jpg"},"post-thumbnail":{"file":"IMG_20240603_100502-300x125.jpg","width":300,"height":125,"filesize":38859,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-300x125.jpg"},"featured-header":{"file":"IMG_20240603_100502-300x125.jpg","width":300,"height":125,"filesize":38859,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-300x125.jpg"},"featured-slider":{"file":"IMG_20240603_100502-644x320.jpg","width":644,"height":320,"filesize":76482,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-644x320.jpg"},"full":{"file":"IMG_20240603_100502-scaled.jpg","width":2560,"height":1915,"mime_type":"image\/jpeg","source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-scaled.jpg"}},"image_meta":{"aperture":"1.79","credit":"","camera":"M2103K19G","caption":"","created_timestamp":"1717409102","copyright":"","focal_length":"4.695","iso":"50","shutter_speed":"0.00575","title":"","orientation":"1","keywords":[]},"original_image":"IMG_20240603_100502.jpg"},"post":9146,"source_url":"https:\/\/www.ugt.cat\/jubilats\/wp-content\/uploads\/2024\/06\/IMG_20240603_100502-scaled.jpg","filename":"IMG_20240603_100502.jpg","filesize":795661,"_links":{"self":[{"href":"https:\/\/www.ugt.cat\/jubilats\/wp-json\/wp\/v2\/media\/9183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ugt.cat\/jubilats\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.ugt.cat\/jubilats\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.ugt.cat\/jubilats\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ugt.cat\/jubilats\/wp-json\/wp\/v2\/comments?post=9183"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":9146,"href":"https:\/\/www.ugt.cat\/jubilats\/wp-json\/wp\/v2\/posts\/9146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}